{"id":8564,"date":"2021-04-09T15:57:16","date_gmt":"2021-04-09T13:57:16","guid":{"rendered":"https:\/\/sjoafamilierafting.no\/?page_id=8564"},"modified":"2024-08-30T19:40:04","modified_gmt":"2024-08-30T17:40:04","slug":"ordering","status":"publish","type":"page","link":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/","title":{"rendered":"Ordering"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;0%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;heading&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;heading&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1643622270298{margin-top: -8px !important;margin-bottom: -8px !important;}&#8221;]\n<h2>Order family rafting<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25&#8243;][vc_raw_html el_class=&#8221;wave&#8221;]JTNDaW1nJTIwc3JjJTNEJTIyJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDQlMkZTam9hLUZhbWlsaWVyYWZ0aW5nLUJvbGdlLUZJTi5zdmclMjIlMjBhbHQlM0QlMjJCJUMzJUI4bGdlJTIyJTIwd2lkdGglM0QlMjIxMDAlMjIlM0U=[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJsb2FkLXR1cml0b3AlMjIlMjBkYXRhLXNlcnZpY2UlM0QlMjJQMSUyMiUyMGRhdGEtbGFuZyUzRCUyMmVuJTIyJTIwJTIwZGF0YS1lbWJlZCUzRCUyMmJveCUyMiUzRSUzQyUyRmRpdiUzRQ==[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_js]JTNDc2NyaXB0JTIwaWQlM0QlMjJqcy10dXJpdG9wJTIyJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhcHAudHVyaXRvcC5jb20lMkZqcyUyRmxvYWQtdHVyaXRvcC5taW4uanMlMjIlMjBkYXRhLWNvbXBhbnklM0QlMjJTMTEzNyUyMiUyMGRhdGEtZ2ElM0QlMjJubyUyMiUyMGRhdGEtYnV0dG9uY29sb3IlM0QlMjJncmVlbiUyMiUyMGRhdGEtYWZmdGFnJTNEJTIydHRhZmlkJTIyJTNFJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][vc_column_text]<strong>If the day or time, you wish to go rafting, is marked red on the online booking, please contact us directly: <a href=\"mailto:booking@sjoafamilierafting.no\">booking@sjoafamilierafting.no<\/a> or telephone +47 47660680 in order to make the booking.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h1>Order family rafting<\/h1>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhcHAudHVyaXRvcC5jb20lMkZib29raW5nJTJGYm94JTJGUzQ0MCUyRlAxJTJGbm8lM0Z0cyUzRDE2MTc5NzM2MDcwNzMlMjZhbXAlM0JyZXR1cm5VcmwlM0RhSFIwY0hNNkx5OTNkM2N1YzJwdllYSmhablJwYm1jdWJtOHZjbUZtZEdsdVp5OTBkWEl0TVMxcmIzSjBkSFZ5TFhKaFpuUnBibWN0YUdWcFpHRnNMdyUzRCUzRCUyMiUyMG5hbWUlM0QlMjJ0dXJpdG9wLWlmcmFtZS0wJTIyJTIwaGVpZ2h0JTNEJTIyMTIwMCUyMiUyMGNsYXNzJTNEJTIyaWZyYW1lLXJlc2l6YWJsZS10dXJpdG9wJTIyJTIwaWQlM0QlMjJpRnJhbWVSZXNpemVyMCUyMiUyMHNjcm9sbGluZyUzRCUyMm5vJTIyJTIwc3R5bGUlM0QlMjJvdmVyZmxvdyUzQSUyMGhpZGRlbiUzQiUyMGhlaWdodCUzQSUyMDg1MXB4JTNCJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;0%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;&#8230;<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":8367,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-8564","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ordering - Sjoa Familierafting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordering\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;0%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/\" \/>\n<meta property=\"og:site_name\" content=\"Sjoa Familierafting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T17:40:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sjoafamilierafting.no\/wp-content\/uploads\/2021\/04\/fb-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/ordering\\\/\",\"url\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/ordering\\\/\",\"name\":\"Ordering - Sjoa Familierafting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#website\"},\"datePublished\":\"2021-04-09T13:57:16+00:00\",\"dateModified\":\"2024-08-30T17:40:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/ordering\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/ordering\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/ordering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Family rafting\",\"item\":\"https:\\\/\\\/sjoafamilierafting.no\\\/en\\\/family-rafting\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ordering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#website\",\"url\":\"https:\\\/\\\/sjoafamilierafting.no\\\/\",\"name\":\"Sjoa Familierafting\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sjoafamilierafting.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#organization\",\"name\":\"Sjoa Familierafting AS\",\"url\":\"https:\\\/\\\/sjoafamilierafting.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sjoafamilierafting.no\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo_SJOA-Familierafting_3-linjer_vektor_RGB-1.svg\",\"contentUrl\":\"https:\\\/\\\/sjoafamilierafting.no\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo_SJOA-Familierafting_3-linjer_vektor_RGB-1.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Sjoa Familierafting AS\"},\"image\":{\"@id\":\"https:\\\/\\\/sjoafamilierafting.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ordering - Sjoa Familierafting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/","og_locale":"en_US","og_type":"article","og_title":"Ordering","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;0%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;...","og_url":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/","og_site_name":"Sjoa Familierafting","article_modified_time":"2024-08-30T17:40:04+00:00","og_image":[{"width":1200,"height":620,"url":"https:\/\/sjoafamilierafting.no\/wp-content\/uploads\/2021\/04\/fb-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/","url":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/","name":"Ordering - Sjoa Familierafting","isPartOf":{"@id":"https:\/\/sjoafamilierafting.no\/#website"},"datePublished":"2021-04-09T13:57:16+00:00","dateModified":"2024-08-30T17:40:04+00:00","breadcrumb":{"@id":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/ordering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/sjoafamilierafting.no\/en\/"},{"@type":"ListItem","position":2,"name":"Family rafting","item":"https:\/\/sjoafamilierafting.no\/en\/family-rafting\/"},{"@type":"ListItem","position":3,"name":"Ordering"}]},{"@type":"WebSite","@id":"https:\/\/sjoafamilierafting.no\/#website","url":"https:\/\/sjoafamilierafting.no\/","name":"Sjoa Familierafting","description":"","publisher":{"@id":"https:\/\/sjoafamilierafting.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sjoafamilierafting.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sjoafamilierafting.no\/#organization","name":"Sjoa Familierafting AS","url":"https:\/\/sjoafamilierafting.no\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sjoafamilierafting.no\/#\/schema\/logo\/image\/","url":"https:\/\/sjoafamilierafting.no\/wp-content\/uploads\/2021\/04\/Logo_SJOA-Familierafting_3-linjer_vektor_RGB-1.svg","contentUrl":"https:\/\/sjoafamilierafting.no\/wp-content\/uploads\/2021\/04\/Logo_SJOA-Familierafting_3-linjer_vektor_RGB-1.svg","width":"1024","height":"1024","caption":"Sjoa Familierafting AS"},"image":{"@id":"https:\/\/sjoafamilierafting.no\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/pages\/8564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/comments?post=8564"}],"version-history":[{"count":6,"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/pages\/8564\/revisions"}],"predecessor-version":[{"id":10571,"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/pages\/8564\/revisions\/10571"}],"up":[{"embeddable":true,"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/pages\/8367"}],"wp:attachment":[{"href":"https:\/\/sjoafamilierafting.no\/en\/wp-json\/wp\/v2\/media?parent=8564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}